{"id":1315,"date":"2024-12-09T15:39:47","date_gmt":"2024-12-09T18:39:47","guid":{"rendered":"https:\/\/produba.com\/?p=1315"},"modified":"2024-12-09T15:39:47","modified_gmt":"2024-12-09T18:39:47","slug":"mas-de-un-centenar-de-empresarios-productivos-participaron-de-escobar-innova","status":"publish","type":"post","link":"https:\/\/produba.com\/index.php\/2024\/12\/09\/mas-de-un-centenar-de-empresarios-productivos-participaron-de-escobar-innova\/","title":{"rendered":"M\u00e1s de un centenar de empresarios productivos participaron de Escobar Innova"},"content":{"rendered":"\n<h5>El s\u00e1bado pasado culmin\u00f3 el megaevento que nuclea innovaci\u00f3n, producci\u00f3n y tecnolog\u00eda. All\u00ed, en el marco de la Expo Escobar 2024, el gobernador Kicillof y el intendente Sujarchuk mantuvieron un importante encuentro con m\u00e1s de 120 representantes del sector productivo.<\/h5>\n\n\n\n<p>El intendente Ariel Sujarchuk y el gobernador de la provincia de Buenos Aires, Axel Kicillof, participaron el s\u00e1bado pasado de la segunda jornada de <strong>Escobar Innova<\/strong>, el megaevento que re\u00fane innovaci\u00f3n, tecnolog\u00eda, cultura, m\u00fasica y cuidado del ambiente, donde mantuvieron un importante encuentro con representantes del sector productivo.<\/p>\n\n\n\n<p>El gobernador y el intendente se reunieron con m\u00e1s de 120 autoridades de empresas, industrias, bancos y comercios para dialogar, debatir, poner en com\u00fan propuestas y seguir fortaleciendo el compromiso del gobierno provincial y municipal con el desarrollo productivo de la regi\u00f3n. La reuni\u00f3n cont\u00f3 con la presencia de los ministros Carlos Bianco (Gobierno) y Augusto Costa (Producci\u00f3n), la jefa de asesores bonaerense, Cristina \u00c1lvarez Rodr\u00edguez; autoridades de la Uni\u00f3n Industrial de Escobar, la C\u00e1mara de Comercio local y la C\u00e1mara Empresaria de Desarrolladores Urbanos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-1024x682.jpg\" alt=\"\" class=\"wp-image-1316\" srcset=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-1024x682.jpg 1024w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-300x200.jpg 300w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-768x512.jpg 768w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-1440x959.jpg 1440w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-1200x799.jpg 1200w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-780x519.jpg 780w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-600x400.jpg 600w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-550x366.jpg 550w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-370x246.jpg 370w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova-255x170.jpg 255w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/axel-sujarchuk-escobar-innova.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>\u201cEn Escobar generamos un Estado promotor que empuja el crecimiento del sector industrial, comercial, de servicios, de emprendedores de la econom\u00eda social\u2026 Y lo hacemos junto con la provincia de Buenos Aires, por eso le agradezco a Axel que siempre est\u00e1 para hablar mano a mano con todos los sectores, porque eso garantiza el buen resultado que terminamos logramos. En las cuatro ediciones de Expo Escobar el gobernador estuvo presente. Y no solo \u00e9l, sino todo su equipo porque de aqu\u00ed surgen una diversidad importante de temas que despu\u00e9s tienen su correlato en el tiempo para concretarlos en hechos reales\u201d<\/em>, expres\u00f3 Sujarchuk.<\/p>\n\n\n\n<p><em>\u201cEl panorama que plantean los empresarios es complicado por el programa econ\u00f3mico que lleva adelante el gobierno nacional. Por eso quiero valorar una vez m\u00e1s el esfuerzo y el trabajo que hace Ariel como intendente. Esta no es una exposici\u00f3n, son seis en una, y permite mostrar los productos locales, la innovaci\u00f3n, la tecnolog\u00eda y el gran tejido industrial que se est\u00e1 desarrollando a pesar de la crisis. Todos los instrumentos de la Provincia est\u00e1n puestos a disposici\u00f3n de cada sector: nuestro banco con sus l\u00edneas de cr\u00e9dito, nuestros ministerios, nuestros programas de incentivos\u2026 Y sabemos que en Escobar contamos con un intendente que potencia esos recursos sumando los propios y promoviendo el progreso\u201d<\/em>, afirm\u00f3 Kicillof.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-1024x685.jpg\" alt=\"\" class=\"wp-image-1319\" srcset=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-1024x685.jpg 1024w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-300x201.jpg 300w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-768x514.jpg 768w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-780x522.jpg 780w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-600x401.jpg 600w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-550x368.jpg 550w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-370x248.jpg 370w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E-255x171.jpg 255w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-de-E.jpg 1070w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Finalizada la reuni\u00f3n con empresarios, Kicillof y Sujarchuk recorrieron el Pabell\u00f3n Industrial, donde visitaron diversos stands que reflejan la innovaci\u00f3n y el potencial productivo del distrito, donde se destacan las empresas Pradecon Racing, Grupo Govan, Denver Farma, FAEN, Suru-Epson, y Pixart, adem\u00e1s del stand central de Escobar Innova en el Pabell\u00f3n 2, que exhibe proyectos y soluciones tecnol\u00f3gicas desarrolladas por el Municipio.<\/p>\n\n\n\n<p>Luego, en el espacio del Registro de las Personas de la Provincia de Buenos Aires, Sujarchuk y Kicillof entregaron partidas de nacimiento a vecinos y vecinas de Escobar y Pilar a trav\u00e9s del programa provincial \u201cMi Identidad, Mi Derecho\u201d dirigido a aquellas personas que no obtuvieron este documento al momento de nacer. Y posteriormente firmaron un acta de ejecuci\u00f3n de asistencia t\u00e9cnica y financiera entre el Municipio de Escobar y el Consejo Federal de Inversiones (CFI), representado por Cristina \u00c1lvarez Rodr\u00edguez. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"856\" height=\"573\" src=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2.jpg\" alt=\"\" class=\"wp-image-1317\" srcset=\"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2.jpg 856w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-300x201.jpg 300w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-768x514.jpg 768w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-780x522.jpg 780w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-600x402.jpg 600w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-550x368.jpg 550w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-370x248.jpg 370w, https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-2-255x171.jpg 255w\" sizes=\"(max-width: 856px) 100vw, 856px\" \/><\/figure>\n\n\n\n<p>Escobar Innova se desarroll\u00f3 entre el jueves 5 y el s\u00e1bado 7 y cont\u00f3 con una agenda cargada de propuestas \u00fanicas: la 4\u00aa edici\u00f3n de Expo Escobar 2024, TechFest, la 9\u00aa Feria del Libro de Escobar, el Mercado de Oportunidades Navide\u00f1o, la Experiencia Inmersiva Van Gogh e Innova Fest. Las actividades comenzaban a las 10 en el Predio Floral de Bel\u00e9n de Escobar (Mateo Gelves 1050) y se extendieron hasta la medianoche con m\u00fasica y entretenimiento para toda la familia.<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado pasado culmin\u00f3 el megaevento que nuclea innovaci\u00f3n, producci\u00f3n y tecnolog\u00eda. All\u00ed, en el marco de la Expo Escobar 2024, el gobernador Kicillof y el intendente Sujarchuk mantuvieron un importante encuentro con m\u00e1s de 120 representantes del sector productivo. El intendente Ariel Sujarchuk y el gobernador de la provincia de Buenos Aires, Axel Kicillof, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":1318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-featured-post":"","loftocean-like-count":0,"loftocean-view-count":174,"loftocean_coauthors":"","alpaca_post_content_reading_setting":"","alpaca_reading_speed_per_minute":0,"alpaca_reading_speed_unit":"","alpaca_single_post_template_layout":""},"categories":[4,6,3],"tags":[170,68,51,169,294,295,42],"loftoceanMetas":{"readingTime":"3 minutos de lectura","authorName":"ProduBA","categories":[{"name":"Desarrollo Local","link":"https:\/\/produba.com\/index.php\/category\/desarrollo_local\/","count":247},{"name":"Municipios","link":"https:\/\/produba.com\/index.php\/category\/municipios\/","count":434},{"name":"Producci\u00f3n","link":"https:\/\/produba.com\/index.php\/category\/produccion\/","count":461}],"date":"9 de diciembre de 2024","featuredImageSRC":"https:\/\/produba.com\/wp-content\/uploads\/2024\/12\/\u00a1Ya-arranco-Escobar-Innova-Hoy-dimos-inicio-al-mega-evento-del-ano.-Durante-los-proximos-dias-podras-disfrutar-de-Expo-Escobar-2024-De-10-a-18-hs.-TechFest-De-10-a-18-hs.-9a-Feria-del-Libro-1-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/posts\/1315"}],"collection":[{"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/comments?post=1315"}],"version-history":[{"count":1,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/posts\/1315\/revisions"}],"predecessor-version":[{"id":1320,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/posts\/1315\/revisions\/1320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/media\/1318"}],"wp:attachment":[{"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/media?parent=1315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/categories?post=1315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/produba.com\/index.php\/wp-json\/wp\/v2\/tags?post=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}